{"id":159861,"date":"2025-12-12T17:30:58","date_gmt":"2025-12-12T15:30:58","guid":{"rendered":"https:\/\/exlibris.ee\/toode\/real-life-global-intermediate-test-book-test-audio-cd-pack\/"},"modified":"2026-05-13T04:09:09","modified_gmt":"2026-05-13T01:09:09","slug":"real-life-global-intermediate-test-book-test-audio-cd-pack","status":"publish","type":"product","link":"https:\/\/exlibris.ee\/ru\/produkt\/real-life-global-intermediate-test-book-test-audio-cd-pack\/","title":{"rendered":"Real life Global Intermediate Test Book &amp; Test Audio CD Pack"},"content":{"rendered":"<p>Placement Tests (Elementary\/Pre-intermediate and Pre-intermediate\/Intermediate.<\/p>\n<p>\u2022 12 short tests (one per unit), in version A and B.<br \/>\n\u2022 Six language and skills tests (one every two units), in version A and B.<br \/>\n\u2022 Speaking tests (for every unit)<br \/>\n\u2022 Writing tests (one for every two units).<br \/>\n\u2022 Mid-year and end-of-year progress tests.<br \/>\n\u2022 Audio for the listening comprehension tasks.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Placement Tests (Elementary\/Pre-intermediate and Pre-intermediate\/Intermediate. \u2022 12 short tests (one per unit), in version A and B. \u2022 Six language and skills tests (one every two units), in version A and B. \u2022 Speaking tests (for every unit) \u2022 Writing&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[63],"product_tag":[],"series":[],"publisher":[{"id":62,"name":"Pearson","slug":"pearson"}],"class_list":{"0":"post-159861","1":"product","2":"type-product","3":"status-publish","5":"product_cat-courses-for-secondary-school","6":"publisher-pearson","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product\/159861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/media?parent=159861"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_brand?post=159861"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=159861"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=159861"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/series?post=159861"},{"taxonomy":"publisher","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/publisher?post=159861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}