{"id":47365,"date":"2023-05-19T12:25:25","date_gmt":"2023-05-19T09:25:25","guid":{"rendered":"https:\/\/exlibris.ee\/toode\/im-beruf-neu-fachwortschatztrainer-transport-und-lager\/"},"modified":"2026-05-11T22:47:53","modified_gmt":"2026-05-11T19:47:53","slug":"im-beruf-neu-fachwortschatztrainer-transport-und-lager","status":"publish","type":"product","link":"https:\/\/exlibris.ee\/ru\/produkt\/im-beruf-neu-fachwortschatztrainer-transport-und-lager\/","title":{"rendered":"Im Beruf NEU  Fachwortschatztrainer Transport und Lager"},"content":{"rendered":"<p>F\u00fcr Lernende in allgemein- oder berufssprachlichen Kursen, die zus\u00e4tzlich den Fachwortschatz Transport und Lager erwerben wollen (auch zum Selbstlernen geeignet).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Lernende in allgemein- oder berufssprachlichen Kursen, die zus\u00e4tzlich den Fachwortschatz Transport und Lager erwerben wollen (auch zum Selbstlernen geeignet).<\/p>\n","protected":false},"featured_media":57418,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[885],"product_tag":[],"series":[{"id":1172,"name":"Im Beruf NEU","slug":"im-beruf-neu"}],"publisher":[{"id":497,"name":"Hueber Verlag","slug":"hueber-verlag"}],"class_list":{"0":"post-47365","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-berufssprache","7":"series-im-beruf-neu","8":"publisher-hueber-verlag","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product\/47365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/media\/57418"}],"wp:attachment":[{"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/media?parent=47365"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_brand?post=47365"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=47365"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=47365"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/series?post=47365"},{"taxonomy":"publisher","embeddable":true,"href":"https:\/\/exlibris.ee\/ru\/wp-json\/wp\/v2\/publisher?post=47365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}